{"id":11643,"date":"2014-10-17T06:49:55","date_gmt":"2014-10-17T06:49:55","guid":{"rendered":"https:\/\/clone.arsacs.com\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/"},"modified":"2021-07-20T14:41:51","modified_gmt":"2021-07-20T18:41:51","slug":"les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits","status":"publish","type":"post","link":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/","title":{"rendered":"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits"},"content":{"rendered":"<p>Le 17 octobre,2014- Suite \u00e0 une visite d&#8217;Olivier Lambercy, un chercheur suisse venu \u00e0 Saguenay en septembre 2012 pr\u00e9senter les travaux de recherche de son laboratoire, nous sommes heureux de constater que les travaux pr\u00e9liminaires ont port\u00e9s fruits. Nous d\u00e9butons le processus d&#8217;analyse des r\u00e9sultats de son outil pour l&#8217;ensemble de la cohorte mais d\u00e9j\u00e0 les r\u00e9sultats du projet pilote sont prometteurs. <a href=\"https:\/\/arsacs.com\/media\/Meeting%20Skype_Zurich.pdf\" target=\"_blank\" rel=\"noopener\">Test \u00e0 Saguenay<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 17 octobre,2014- Suite \u00e0 une visite d&#8217;Olivier Lambercy, un chercheur suisse venu \u00e0 Saguenay en septembre 2012 pr\u00e9senter les travaux de recherche de son laboratoire, nous sommes heureux de constater que les travaux pr\u00e9liminaires ont port\u00e9s fruits. Nous d\u00e9butons le processus d&#8217;analyse des r\u00e9sultats de son outil pour l&#8217;ensemble de la cohorte mais d\u00e9j\u00e0 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-11643","post","type-post","status-publish","format-standard","hentry","category-recherche-2014"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits - ARSACS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits - ARSACS\" \/>\n<meta property=\"og:description\" content=\"Le 17 octobre,2014- Suite \u00e0 une visite d&#8217;Olivier Lambercy, un chercheur suisse venu \u00e0 Saguenay en septembre 2012 pr\u00e9senter les travaux de recherche de son laboratoire, nous sommes heureux de constater que les travaux pr\u00e9liminaires ont port\u00e9s fruits. Nous d\u00e9butons le processus d&#8217;analyse des r\u00e9sultats de son outil pour l&#8217;ensemble de la cohorte mais d\u00e9j\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSACS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100044457429916\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-17T06:49:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-20T18:41:51+00:00\" \/>\n<meta name=\"author\" content=\"ARSACS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ARSACS\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/\"},\"author\":{\"name\":\"ARSACS\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/person\\\/93b66d6b897bfa131622d04b767b15f1\"},\"headline\":\"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits\",\"datePublished\":\"2014-10-17T06:49:55+00:00\",\"dateModified\":\"2021-07-20T18:41:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#organization\"},\"articleSection\":[\"Recherche 2014\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/\",\"url\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/\",\"name\":\"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits - ARSACS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#website\"},\"datePublished\":\"2014-10-17T06:49:55+00:00\",\"dateModified\":\"2021-07-20T18:41:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arsacs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#website\",\"url\":\"https:\\\/\\\/arsacs.com\\\/\",\"name\":\"Fondation de l'Ataxie Charlevoix-Saguenay\",\"description\":\"Research That Heals\",\"publisher\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arsacs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#organization\",\"name\":\"ARSACS\",\"url\":\"https:\\\/\\\/arsacs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo_ARSACS_fr_flat.png\",\"contentUrl\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo_ARSACS_fr_flat.png\",\"width\":291,\"height\":84,\"caption\":\"ARSACS\"},\"image\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100044457429916\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/person\\\/93b66d6b897bfa131622d04b767b15f1\",\"name\":\"ARSACS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g\",\"caption\":\"ARSACS\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits - ARSACS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/","og_locale":"fr_FR","og_type":"article","og_title":"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits - ARSACS","og_description":"Le 17 octobre,2014- Suite \u00e0 une visite d&#8217;Olivier Lambercy, un chercheur suisse venu \u00e0 Saguenay en septembre 2012 pr\u00e9senter les travaux de recherche de son laboratoire, nous sommes heureux de constater que les travaux pr\u00e9liminaires ont port\u00e9s fruits. Nous d\u00e9butons le processus d&#8217;analyse des r\u00e9sultats de son outil pour l&#8217;ensemble de la cohorte mais d\u00e9j\u00e0 [&hellip;]","og_url":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/","og_site_name":"ARSACS","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100044457429916","article_published_time":"2014-10-17T06:49:55+00:00","article_modified_time":"2021-07-20T18:41:51+00:00","author":"ARSACS","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ARSACS"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/#article","isPartOf":{"@id":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/"},"author":{"name":"ARSACS","@id":"https:\/\/arsacs.com\/#\/schema\/person\/93b66d6b897bfa131622d04b767b15f1"},"headline":"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits","datePublished":"2014-10-17T06:49:55+00:00","dateModified":"2021-07-20T18:41:51+00:00","mainEntityOfPage":{"@id":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/arsacs.com\/#organization"},"articleSection":["Recherche 2014"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/","url":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/","name":"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits - ARSACS","isPartOf":{"@id":"https:\/\/arsacs.com\/#website"},"datePublished":"2014-10-17T06:49:55+00:00","dateModified":"2021-07-20T18:41:51+00:00","breadcrumb":{"@id":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arsacs.com\/fr\/les-travaux-preliminaires-avec-olivier-lambercy-de-zurich-ont-porte-fruits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arsacs.com\/"},{"@type":"ListItem","position":2,"name":"Les travaux pr\u00e9liminaires avec Olivier Lambercy de Zurich ont port\u00e9 fruits"}]},{"@type":"WebSite","@id":"https:\/\/arsacs.com\/#website","url":"https:\/\/arsacs.com\/","name":"Fondation de l'Ataxie Charlevoix-Saguenay","description":"Research That Heals","publisher":{"@id":"https:\/\/arsacs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arsacs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/arsacs.com\/#organization","name":"ARSACS","url":"https:\/\/arsacs.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arsacs.com\/#\/schema\/logo\/image\/","url":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/06\/logo_ARSACS_fr_flat.png","contentUrl":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/06\/logo_ARSACS_fr_flat.png","width":291,"height":84,"caption":"ARSACS"},"image":{"@id":"https:\/\/arsacs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100044457429916"]},{"@type":"Person","@id":"https:\/\/arsacs.com\/#\/schema\/person\/93b66d6b897bfa131622d04b767b15f1","name":"ARSACS","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g","caption":"ARSACS"}}]}},"_links":{"self":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts\/11643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/comments?post=11643"}],"version-history":[{"count":1,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts\/11643\/revisions"}],"predecessor-version":[{"id":14862,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts\/11643\/revisions\/14862"}],"wp:attachment":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/media?parent=11643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/categories?post=11643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/tags?post=11643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}