{"id":11696,"date":"2017-02-23T20:37:35","date_gmt":"2017-02-23T20:37:35","guid":{"rendered":"https:\/\/clone.arsacs.com\/demande-de-bourses-dici-le-25-mai-2017\/"},"modified":"2017-02-23T20:37:35","modified_gmt":"2017-02-23T20:37:35","slug":"demande-de-bourses-dici-le-25-mai-2017","status":"publish","type":"post","link":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/","title":{"rendered":"Demande de bourses d&#8217;ici le 25 mai 2017"},"content":{"rendered":"<p>Afin d&#8217;encourager et d&#8217;acc\u00e9l\u00e9rer le d\u00e9veloppement d&#8217;un traitement pour l&#8217;ARSACS, la Fondation accordera des bourses de recherche\u00a0\u00a0jusqu&#8217;\u00e0 100 000$ pour une p\u00e9riode de 12 mois avec possibilit\u00e9 de renouvellement pour une deuxi\u00e8me ann\u00e9e. Les chercheurs int\u00e9ress\u00e9s doivent soumettre leur demande\u00a0 d&#8217;ici le 25 mai, 2017.\u00a0\u00a0<a href=\"https:\/\/arsacs.com\/files\/Offre_Financement_2017.pdf\">Formulaire de demande<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afin d&#8217;encourager et d&#8217;acc\u00e9l\u00e9rer le d\u00e9veloppement d&#8217;un traitement pour l&#8217;ARSACS, la Fondation accordera des bourses de recherche\u00a0\u00a0jusqu&#8217;\u00e0 100 000$ pour une p\u00e9riode de 12 mois avec possibilit\u00e9 de renouvellement pour une deuxi\u00e8me ann\u00e9e. Les chercheurs int\u00e9ress\u00e9s doivent soumettre leur demande\u00a0 d&#8217;ici le 25 mai, 2017.\u00a0\u00a0Formulaire de demande &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":9633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-11696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demande de bourses d&#039;ici le 25 mai 2017 - ARSACS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demande de bourses d&#039;ici le 25 mai 2017 - ARSACS\" \/>\n<meta property=\"og:description\" content=\"Afin d&#8217;encourager et d&#8217;acc\u00e9l\u00e9rer le d\u00e9veloppement d&#8217;un traitement pour l&#8217;ARSACS, la Fondation accordera des bourses de recherche\u00a0\u00a0jusqu&#8217;\u00e0 100 000$ pour une p\u00e9riode de 12 mois avec possibilit\u00e9 de renouvellement pour une deuxi\u00e8me ann\u00e9e. Les chercheurs int\u00e9ress\u00e9s doivent soumettre leur demande\u00a0 d&#8217;ici le 25 mai, 2017.\u00a0\u00a0Formulaire de demande &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSACS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100044457429916\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-23T20:37:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/02\/bg2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1301\" \/>\n\t<meta property=\"og:image:height\" content=\"1301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ARSACS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ARSACS\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/\"},\"author\":{\"name\":\"ARSACS\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/person\\\/93b66d6b897bfa131622d04b767b15f1\"},\"headline\":\"Demande de bourses d&#8217;ici le 25 mai 2017\",\"datePublished\":\"2017-02-23T20:37:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/\"},\"wordCount\":66,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/bg2.png\",\"articleSection\":[\"Archives Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/\",\"url\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/\",\"name\":\"Demande de bourses d'ici le 25 mai 2017 - ARSACS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/bg2.png\",\"datePublished\":\"2017-02-23T20:37:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/bg2.png\",\"contentUrl\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/bg2.png\",\"width\":1301,\"height\":1301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/fr\\\/demande-de-bourses-dici-le-25-mai-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arsacs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demande de bourses d&#8217;ici le 25 mai 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#website\",\"url\":\"https:\\\/\\\/arsacs.com\\\/\",\"name\":\"Fondation de l'Ataxie Charlevoix-Saguenay\",\"description\":\"Research That Heals\",\"publisher\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arsacs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#organization\",\"name\":\"ARSACS\",\"url\":\"https:\\\/\\\/arsacs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo_ARSACS_fr_flat.png\",\"contentUrl\":\"https:\\\/\\\/arsacs.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo_ARSACS_fr_flat.png\",\"width\":291,\"height\":84,\"caption\":\"ARSACS\"},\"image\":{\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100044457429916\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arsacs.com\\\/#\\\/schema\\\/person\\\/93b66d6b897bfa131622d04b767b15f1\",\"name\":\"ARSACS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g\",\"caption\":\"ARSACS\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demande de bourses d'ici le 25 mai 2017 - ARSACS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/","og_locale":"fr_FR","og_type":"article","og_title":"Demande de bourses d'ici le 25 mai 2017 - ARSACS","og_description":"Afin d&#8217;encourager et d&#8217;acc\u00e9l\u00e9rer le d\u00e9veloppement d&#8217;un traitement pour l&#8217;ARSACS, la Fondation accordera des bourses de recherche\u00a0\u00a0jusqu&#8217;\u00e0 100 000$ pour une p\u00e9riode de 12 mois avec possibilit\u00e9 de renouvellement pour une deuxi\u00e8me ann\u00e9e. Les chercheurs int\u00e9ress\u00e9s doivent soumettre leur demande\u00a0 d&#8217;ici le 25 mai, 2017.\u00a0\u00a0Formulaire de demande &nbsp; &nbsp;","og_url":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/","og_site_name":"ARSACS","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100044457429916","article_published_time":"2017-02-23T20:37:35+00:00","og_image":[{"width":1301,"height":1301,"url":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/02\/bg2.png","type":"image\/jpeg"}],"author":"ARSACS","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ARSACS"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#article","isPartOf":{"@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/"},"author":{"name":"ARSACS","@id":"https:\/\/arsacs.com\/#\/schema\/person\/93b66d6b897bfa131622d04b767b15f1"},"headline":"Demande de bourses d&#8217;ici le 25 mai 2017","datePublished":"2017-02-23T20:37:35+00:00","mainEntityOfPage":{"@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/"},"wordCount":66,"commentCount":0,"publisher":{"@id":"https:\/\/arsacs.com\/#organization"},"image":{"@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/02\/bg2.png","articleSection":["Archives Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/","url":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/","name":"Demande de bourses d'ici le 25 mai 2017 - ARSACS","isPartOf":{"@id":"https:\/\/arsacs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#primaryimage"},"image":{"@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/02\/bg2.png","datePublished":"2017-02-23T20:37:35+00:00","breadcrumb":{"@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#primaryimage","url":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/02\/bg2.png","contentUrl":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/02\/bg2.png","width":1301,"height":1301},{"@type":"BreadcrumbList","@id":"https:\/\/arsacs.com\/fr\/demande-de-bourses-dici-le-25-mai-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arsacs.com\/"},{"@type":"ListItem","position":2,"name":"Demande de bourses d&#8217;ici le 25 mai 2017"}]},{"@type":"WebSite","@id":"https:\/\/arsacs.com\/#website","url":"https:\/\/arsacs.com\/","name":"Fondation de l'Ataxie Charlevoix-Saguenay","description":"Research That Heals","publisher":{"@id":"https:\/\/arsacs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arsacs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/arsacs.com\/#organization","name":"ARSACS","url":"https:\/\/arsacs.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arsacs.com\/#\/schema\/logo\/image\/","url":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/06\/logo_ARSACS_fr_flat.png","contentUrl":"https:\/\/arsacs.com\/wp-content\/uploads\/2021\/06\/logo_ARSACS_fr_flat.png","width":291,"height":84,"caption":"ARSACS"},"image":{"@id":"https:\/\/arsacs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100044457429916"]},{"@type":"Person","@id":"https:\/\/arsacs.com\/#\/schema\/person\/93b66d6b897bfa131622d04b767b15f1","name":"ARSACS","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3b226aca332e58d41ec45fa04620bcbd869d2e4e661cacde31eeb3ae6a5708d?s=96&d=mm&r=g","caption":"ARSACS"}}]}},"_links":{"self":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts\/11696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/comments?post=11696"}],"version-history":[{"count":0,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/posts\/11696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/media\/9633"}],"wp:attachment":[{"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/media?parent=11696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/categories?post=11696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arsacs.com\/fr\/wp-json\/wp\/v2\/tags?post=11696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}